{"id":1114,"date":"2019-05-28T17:34:00","date_gmt":"2019-05-28T15:34:00","guid":{"rendered":"https:\/\/mensandbeauty.com\/tienda\/?post_type=product&#038;p=1114"},"modified":"2020-04-17T10:44:56","modified_gmt":"2020-04-17T08:44:56","slug":"cera-pelo-hombre-grooming-clay-shave-barbers-spa","status":"publish","type":"product","link":"https:\/\/mensandbeauty.com\/tienda\/cera-pelo-hombre-grooming-clay-shave-barbers-spa\/","title":{"rendered":"Cera de Pelo de Arcilla para Hombre \u00abGrooming\u00bb\u3010SHAVE Barbers &#038; Spa\u3011"},"content":{"rendered":"<h2>Cera de Pelo de Arcilla para Hombre \u00abGrooming\u00bb de SHAVE Barbers &amp; Spa<\/h2>\n<p>Dale una vuelta de tuerca a la forma en que te peinas. Consigue un acabado natural mientras peinas tu pelo como m\u00e1s te gusta.<\/p>\n<h3>\u00bfC\u00f3mo se usa?<\/h3>\n<p>Vale con aplicar una peque\u00f1a cantidad en la palma de la mano y pasar desde la ra\u00edz del cabello hasta la punta, habiendo calentado previamente la mano para una aplicaci\u00f3n m\u00e1s sencilla. Tras esto, peinar como gustes.<\/p>\n<h3>\u00bfQu\u00e9 se siente cuando te lo aplicas?<\/h3>\n<p>Notar\u00e1s como tu pelo empieza a coger fuerza, lo f\u00e1cil que resulta peinarse y la agradable textura que consigues durante todo el d\u00eda.<\/p>\n<h3>\u00bfPor qu\u00e9 comprarlo?<\/h3>\n<p>Proporciona un acabado mate seco para el engrosamiento y control del cabello. Consigue los mejores peinados d\u00e1ndole a tu pelo una mayor textura y definici\u00f3n.<\/p>\n<h3>Contenido<\/h3>\n<p>100 ml.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfLe dedicas mucho tiempo a peinarte? \u00bfDespu\u00e9s de un rato delante del espejo, no acabas satisfecho? Gracias a esta cera de pelo para hombre \u00abGrooming Clay\u00bb conseguir\u00e1s los mejores peinados en muy poco tiempo. Aplicar, peinar y listo. Adem\u00e1s de rapidez, calidad. Consigue m\u00e1xima definici\u00f3n y una textura sorprendente desde la primera aplicaci\u00f3n. Proporciona un acabado mate seco para los cabellos m\u00e1s grasos y proporciona un control total del cabello.<\/p>\n<p><a href=\"https:\/\/emojipedia.org\/white-heavy-check-mark\/\"><span class=\"emoji\">\u2705\u00a0<\/span><\/a><strong>Acabado Mate Seco.<\/strong><\/p>\n<p><a href=\"https:\/\/emojipedia.org\/white-heavy-check-mark\/\"><span class=\"emoji\">\u2705\u00a0<\/span><\/a><strong>M\u00e1ximo Control<\/strong> del Cabello.<\/p>\n<p><a href=\"https:\/\/emojipedia.org\/white-heavy-check-mark\/\"><span class=\"emoji\">\u2705\u00a0<\/span><\/a><strong>Textura \u00danica<\/strong> del Cabello.<\/p>\n","protected":false},"featured_media":1189,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[835],"product_tag":[996],"class_list":["post-1114","product","type-product","status-publish","has-post-thumbnail","product_cat-moldeadores-pelo-hombre","product_tag-shave-barbers-spa-2","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/product\/1114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/comments?post=1114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/media\/1189"}],"wp:attachment":[{"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/media?parent=1114"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/product_brand?post=1114"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/product_cat?post=1114"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mensandbeauty.com\/tienda\/wp-json\/wp\/v2\/product_tag?post=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}